{"id":14,"date":"2025-04-09T10:25:28","date_gmt":"2025-04-09T08:25:28","guid":{"rendered":"https:\/\/nadinemeissner.com\/?page_id=14"},"modified":"2025-12-12T12:11:48","modified_gmt":"2025-12-12T11:11:48","slug":"startseite","status":"publish","type":"page","link":"https:\/\/nadinemeissner.com\/en\/","title":{"rendered":"Startseite"},"content":{"rendered":"<div class=\"grve-section grve-primary-1\" data-section-title=\"\" data-section-type=\"fullwidth-background\" data-image-type=\"none\" data-full-height=\"no\"  style=\"padding-top: 120px;padding-bottom: 120px;margin-bottom: 0px;\"><div class=\"grve-row grve-bookmark\"><div class=\"wpb_column grve-column grve-bookmark grve-column-1\"><h1 class=\"grve-element grve-align-left grve-title-line grve-h1\" style=\"\"><span>A VERY  WARM WELCOME!<\/span><\/h1><div class=\"grve-element grve-text\"><p>Welcome to Nadine Meissner's farm in the beautiful Sauerland region, where horses are cared for in a holistic training and rehabilitation environment.<\/p>\n<p class=\"translation-block\">As an expert in Lazaris Nerve Release, Hoof Care and Equine Fascia Therapy, Nadine creates a strong health foundation for horses through individualised and comprehensive treatment. She is passionate about helping horses to develop in a biodynamically and biomechanically healthy way.<\/p>\n<p class=\"translation-block\">Find out more about her philosophy of equine health and her comprehensive services as a certified HHHL instructor, HUF counsellor and equine osteopath.<\/p>\n<\/div><\/div> <\/div><div class=\"grve-background-wrapper\"><\/div><\/div><div class=\"grve-section grve-primary-1\" data-section-title=\"\" data-section-type=\"fullwidth-background\" data-image-type=\"parallax\" data-full-height=\"no\"  style=\"padding-top: 120px;padding-bottom: 120px;margin-bottom: 0px;\"><div class=\"grve-row grve-bookmark\"><div class=\"wpb_column grve-column grve-bookmark grve-column-1\"><div class=\"vc_empty_space\"   style=\"height: 100px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div> <\/div><div class=\"grve-background-wrapper\">  <div class=\"grve-bg-image\" data-stellar-ratio=\"0.5\"  style=\"background-image: url(https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-1920x1280.jpg);\"><\/div><\/div><\/div><div class=\"grve-section grve-primary-1\" data-section-title=\"\" data-section-type=\"fullwidth-background\" data-image-type=\"none\" data-full-height=\"no\"  style=\"padding-top: 120px;padding-bottom: 120px;margin-bottom: 0px;\"><div class=\"grve-row grve-bookmark\"><div class=\"wpb_column grve-column grve-bookmark grve-column-1\"><div class=\"grve-element grve-text\"><p><h2 class=\"grve-element grve-align-left grve-title-line grve-h2\" style=\"\"><span>ABOUT ME<\/span><\/h2><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-o-shape-group vc_tta-tabs-position-top vc_tta-controls-align-left\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\" role=\"tablist\"><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><\/div><\/div><\/div><\/div>\n<\/div><\/div><div class=\"wpb_column grve-column grve-bookmark grve-column-1-3\"><div class=\"grve-element grve-image grve-align-left\" style=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_CLVT4251-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_CLVT4251-225x300.jpg 225w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_CLVT4251-768x1024.jpg 768w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_CLVT4251-1152x1536.jpg 1152w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_CLVT4251-9x12.jpg 9w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_CLVT4251-1440x1920.jpg 1440w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_CLVT4251.jpg 1530w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/div><\/div><div class=\"wpb_column grve-column grve-bookmark grve-column-2-3\"><h3 class=\"grve-element grve-align-left grve-title-no-line grve-h3\" style=\"\"><span>Nadine Meissner<\/span><\/h3><div class=\"grve-element grve-text\"><ul>\n<li>Lazaris Nerve Release Practitioner<\/li>\n<li>HUF(rehe)-Berater<\/li>\n<li>Equine ostheopath<\/li>\n<li>certified HHHL instructor<\/li>\n<\/ul>\n<\/div><div class=\"grve-element grve-align-left\"><a class=\"grve-btn grve-btn-large grve-square grve-bg-primary-1\" href=\"https:\/\/nadinemeissner.com\/en\/ueber-mich\/\" target=\"_self\" style=\"\"><span>MORE<\/span><\/a><\/div><\/div><div class=\"wpb_column grve-column grve-bookmark grve-column-1\"><\/div> <\/div><div class=\"grve-background-wrapper\"><\/div><\/div><div class=\"grve-section grve-primary-1\" data-section-title=\"\" data-section-type=\"fullwidth-background\" data-image-type=\"parallax\" data-full-height=\"no\"><div class=\"grve-row grve-bookmark\"><div class=\"wpb_column grve-column grve-bookmark grve-column-1\"><div class=\"vc_empty_space\"   style=\"height: 42px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"grve-element grve-text\"><p><h2 class=\"grve-element grve-align-left grve-title-line grve-h2\" style=\"\"><span>THERAPY - TRAINING - REHA<\/span><\/h2><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-o-shape-group vc_tta-tabs-position-top vc_tta-controls-align-left\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\" role=\"tablist\"><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><\/div><\/div><\/div><\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"grve-element grve-text\"><p>Find out more about our range of therapies, our training programmes and our rehabilitation options for serious injuries:<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><div class=\"wpb_column grve-column grve-bookmark grve-column-1-3\"><div class=\"grve-element grve-image grve-align-left\" style=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1260\" src=\"https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_IMG_E1798-scaled-e1762425281493.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_IMG_E1798-scaled-e1762425281493.jpg 1920w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_IMG_E1798-scaled-e1762425281493-300x197.jpg 300w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_IMG_E1798-scaled-e1762425281493-1024x672.jpg 1024w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_IMG_E1798-scaled-e1762425281493-768x504.jpg 768w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_IMG_E1798-scaled-e1762425281493-1536x1008.jpg 1536w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/11\/Nadine-Meissner_IMG_E1798-scaled-e1762425281493-18x12.jpg 18w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><div class=\"vc_empty_space\"   style=\"height: 8px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><h3 class=\"grve-element grve-align-left grve-title-no-line grve-h3\" style=\"\"><span>THERAPY<\/span><\/h3><div class=\"grve-element grve-text\"><ul>\n<li>Lazaris Nerve Release<\/li>\n<li>Fascia therapy<\/li>\n<li>Craniodynamic<\/li>\n<li>Hoof Consulting<\/li>\n<\/ul>\n<\/div><div class=\"grve-element grve-align-left\"><a class=\"grve-btn grve-btn-medium grve-square grve-bg-primary-1\" href=\"https:\/\/nadinemeissner.com\/en\/therapie\/\" target=\"_self\" style=\"\"><span>MORE<\/span><\/a><\/div><\/div><div class=\"wpb_column grve-column grve-bookmark grve-column-1-3\"><div class=\"grve-element grve-image grve-align-left\" style=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/young-woman-in-protective-hat-with-her-horse-in-ag-2025-03-18-19-58-36-utc-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/young-woman-in-protective-hat-with-her-horse-in-ag-2025-03-18-19-58-36-utc-scaled.jpg 2560w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/young-woman-in-protective-hat-with-her-horse-in-ag-2025-03-18-19-58-36-utc-300x200.jpg 300w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/young-woman-in-protective-hat-with-her-horse-in-ag-2025-03-18-19-58-36-utc-1024x683.jpg 1024w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/young-woman-in-protective-hat-with-her-horse-in-ag-2025-03-18-19-58-36-utc-768x512.jpg 768w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/young-woman-in-protective-hat-with-her-horse-in-ag-2025-03-18-19-58-36-utc-1536x1024.jpg 1536w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/young-woman-in-protective-hat-with-her-horse-in-ag-2025-03-18-19-58-36-utc-18x12.jpg 18w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/young-woman-in-protective-hat-with-her-horse-in-ag-2025-03-18-19-58-36-utc-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><div class=\"vc_empty_space\"   style=\"height: 8px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><h3 class=\"grve-element grve-align-left grve-title-no-line grve-h3\" style=\"\"><span>TRAINING<\/span><\/h3><div class=\"grve-element grve-text\"><ul>\n<li class=\"translation-block\">Happy Horse Happy Life<\/li>\n<li>Lesson &amp; Clinic Pricing<\/li>\n<\/ul>\n<\/div><div class=\"grve-element grve-align-left\"><a class=\"grve-btn grve-btn-medium grve-square grve-bg-primary-1\" href=\"https:\/\/nadinemeissner.com\/en\/training\/\" target=\"_self\" style=\"\"><span>MORE<\/span><\/a><\/div><\/div><div class=\"wpb_column grve-column grve-bookmark grve-column-1-3\"><div class=\"grve-element grve-image grve-align-left\" style=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-scaled.jpg 2560w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-300x200.jpg 300w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-1024x683.jpg 1024w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-768x512.jpg 768w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-1536x1024.jpg 1536w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-18x12.jpg 18w, https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/horse-a-photo-of-a-horse-in-natural-setting-2025-04-06-11-50-52-utc-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><div class=\"vc_empty_space\"   style=\"height: 8px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><h3 class=\"grve-element grve-align-left grve-title-no-line grve-h3\" style=\"\"><span>REHA<\/span><\/h3><div class=\"grve-element grve-text\"><ul>\n<li>On-site rehabilitation\n<ul>\n<li>EMR \u2013 Equine Movement Rehabilitation<\/li>\n<li>Hoof injuries \/ Laminitis<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li>Long distance Rehabilitation\n<ul>\n<li>EMR \u2013 Equine Movement Rehabilitation<\/li>\n<li>Hoof injuries \/ Laminitis<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><div class=\"grve-element grve-align-left\"><a class=\"grve-btn grve-btn-medium grve-square grve-bg-primary-1\" href=\"https:\/\/nadinemeissner.com\/en\/reha\/\" target=\"_self\" style=\"\"><span>MORE<\/span><\/a><\/div><\/div><div class=\"wpb_column grve-column grve-bookmark grve-column-1\"><div class=\"vc_empty_space\"   style=\"height: 42px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div> <\/div><div class=\"grve-background-wrapper\">  <div class=\"grve-light-overlay grve-overlay-80\"><\/div>  <div class=\"grve-bg-image\" data-stellar-ratio=\"0.5\"  style=\"background-image: url(https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/silhouette-of-woman-rider-on-horseback-climbing-hi-2025-01-15-12-40-38-utc-1920x1280.jpeg);\"><\/div><\/div><\/div><div class=\"grve-section\" data-section-title=\"\" data-section-type=\"fullwidth-background\" data-image-type=\"none\" data-full-height=\"no\"><div class=\"grve-row grve-bookmark\"><div class=\"wpb_column grve-column grve-bookmark grve-column-1\"><div class=\"vc_empty_space\"   style=\"height: 80px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><h2 class=\"grve-element grve-align-left grve-title-line grve-h2\" style=\"\"><span>Termine ``Am Berg``<\/span><\/h2><div class=\"grve-element grve-text\"><p><strong>Unsere aktuellen Termine im \u00dcberblick:<\/strong><\/p>\n<\/div><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-o-shape-group vc_tta-tabs-position-top vc_tta-controls-align-left vc_custom_1750233084923\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\" role=\"tablist\"><li class=\"vc_tta-tab vc_active\" data-vc-tab role=\"presentation\"><a href=\"#1750232151775-3d9c7a17-d53f\" data-vc-tabs data-vc-container=\".vc_tta\" role=\"tab\" aria-selected=\"false\" id=\"tab-1750232151775-3d9c7a17-d53f\"><span class=\"vc_tta-title-text\">TERMIN X - 01.01.2026<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab role=\"presentation\"><a href=\"#1750232151783-17dc0329-6fa2\" data-vc-tabs data-vc-container=\".vc_tta\" role=\"tab\" aria-selected=\"false\" id=\"tab-1750232151783-17dc0329-6fa2\"><span class=\"vc_tta-title-text\">TERMIN Y - 01.02.2026<\/span><\/a><\/li><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"1750232151775-3d9c7a17-d53f\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1750232151775-3d9c7a17-d53f\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">TERMIN X - 01.01.2026<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"grve-element grve-text\"><p><strong>TERMIN XY &#8211; 01.01.2026<\/strong><\/p>\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p>\n<p>&nbsp;<\/p>\n<\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1750232151783-17dc0329-6fa2\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1750232151783-17dc0329-6fa2\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">TERMIN Y - 01.02.2026<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"grve-element grve-text\"><p><strong>TERMIN XY &#8211; 01.02.2026<\/strong><\/p>\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p>\n<p>&nbsp;<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 80px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div> <\/div><div class=\"grve-background-wrapper\"><\/div><\/div><div class=\"grve-section\" data-section-title=\"\" data-section-type=\"fullwidth-background\" data-image-type=\"none\" data-full-height=\"no\"><div class=\"grve-row grve-bookmark\"><div class=\"wpb_column grve-column grve-bookmark grve-column-1\"><div class=\"vc_empty_space\"   style=\"height: 80px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"grve-element grve-text\"><p><h2 class=\"grve-element grve-align-left grve-title-line grve-h2\" style=\"\"><span>KONTAKT<\/span><\/h2><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-o-shape-group vc_tta-tabs-position-top vc_tta-controls-align-left\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\" role=\"tablist\"><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><\/div><\/div><\/div><\/div>\n<\/div><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-101\"><form id=\"wpforms-form-101\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"101\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/14\" data-token=\"0adb93f620cb7ed2a484d8c02f7fc2ad\" data-token-time=\"1778667651\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/14\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-101-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-101-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-101-field_1-error\" required><label for=\"wpforms-101-field_1\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-101-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-101-field_1-last-error\" required><label for=\"wpforms-101-field_1-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-101-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-101-field_2\">E-Mail-Adresse <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-101-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-101-field_2-error\" required><\/div><div id=\"wpforms-101-field_4-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-101-field_4\">Telefonnummer <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-101-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" step=\"any\" aria-errormessage=\"wpforms-101-field_4-error\" required><\/div>\t\t<div id=\"wpforms-101-field_5-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"5\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-101-field_5\" >Nachricht Kommentar Telefonnummer<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-101-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-101-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-101-field_3\">Kommentar oder Nachricht <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-101-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-101-field_3-error\" required><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-101-field_5-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-101-field_5-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-101-field_5-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"101\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/pages\/14\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-101\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet\u00a0\u2026\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nadinemeissner.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><\/div>  <!-- .wpforms-container --><div class=\"vc_empty_space\"   style=\"height: 80px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div> <\/div><div class=\"grve-background-wrapper\">  <div class=\"grve-light-overlay grve-overlay-80\"><\/div>  <div class=\"grve-bg-image\"   style=\"background-image: url(https:\/\/nadinemeissner.com\/wp-content\/uploads\/2025\/06\/header-1-1920x635.png);\"><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"HERZLICH WILLKOMMENWillkommen auf dem Hof von Nadine Meissner im sch\u00f6nen Sauerland, wo Pferde in einem ganzheitlichen Trainings- und Rehabilitationsumfeld betreut werden. Als Expertin f\u00fcr Lazaris Nerve Release, Hufpflege und Equine Faszientherapie schafft Nadine durch eine individuelle und umfassende Behandlung eine starke gesundheitliche Basis f\u00fcr Pferde. Ihre Passion ist es, Pferden zu helfen, sich biodynamisch und [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":78,"href":"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":228,"href":"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/pages\/14\/revisions\/228"}],"wp:attachment":[{"href":"https:\/\/nadinemeissner.com\/en\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}